{"id":788,"date":"2015-06-25T15:53:26","date_gmt":"2015-06-25T15:53:26","guid":{"rendered":"http:\/\/fragmentsliminaires.net\/?p=788"},"modified":"2022-07-25T18:59:46","modified_gmt":"2022-07-25T17:59:46","slug":"declaration-de-flamme","status":"publish","type":"post","link":"https:\/\/fragmentsliminaires.net\/es\/2015\/06\/25\/declaration-de-flamme\/","title":{"rendered":"d\u00e9claration de flamme"},"content":{"rendered":"<h5><span style=\"color: #808080;\">2011, p\u00f3lvora, carb\u00f3n, papel (75 x 110 cm)<\/span><\/h5>\n<p style=\"text-align: justify;\">Sobre la superficie de cuatro hojas de papel, dos blancas y dos negras, percibimos los contornos de un texto reproducido cuatro veces con la ayuda de un molde : dos veces con p\u00f3lvora, dos veces con carb\u00f3n. La p\u00f3lvora y el carb\u00f3n han sido depositados directamente sobre el papel, sin fijador ni aglutinante, de tal manera que las \u201cpalabras\u201d son ef\u00edmeras, podr\u00edan desaparecer con el viento o con un ligero movimiento. El texto del cual el molde retoma la forma, es el poema \u201cCuarto de hotel\u201d, escrito por Mahmoud Darwish en 1986.<\/p>\n<div id=\"dc_vk_code\" style=\"display: none;\"><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1024x680.jpg\" alt=\"\" class=\"wp-image-2844\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1024x680.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-300x199.jpg 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-768x510.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1536x1020.jpg 1536w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-2048x1360.jpg 2048w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-295x197.jpg 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-1024x682.jpg\" alt=\"\" class=\"wp-image-2889\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-1024x682.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-300x200.jpg 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-768x512.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-295x197.jpg 295w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1.jpg 1282w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4059\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-1024x683.jpg\" alt=\"\" class=\"wp-image-4059\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-1024x683.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-300x200.jpg 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-768x512.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-1536x1024.jpg 1536w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-2048x1365.jpg 2048w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2015\/06\/IMG_6655-295x197.jpg 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-1024x682.jpg\" alt=\"\" class=\"wp-image-2889\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-1024x682.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-300x200.jpg 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-768x512.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1-295x197.jpg 295w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/credits_EPL3-copie-1.jpg 1282w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1024x680.jpg\" alt=\"\" class=\"wp-image-2844\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1024x680.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-300x199.jpg 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-768x510.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-1536x1020.jpg 1536w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-2048x1360.jpg 2048w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/0028-copia-copie-2-295x197.jpg 295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"2846\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-683x1024.jpg\" alt=\"\" class=\"wp-image-2846\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-683x1024.jpg 683w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-200x300.jpg 200w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-768x1152.jpg 768w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-1024x1536.jpg 1024w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-1365x2048.jpg 1365w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2020\/01\/IMG_6416-1-copie-2-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>2011, p\u00f3lvora, carb\u00f3n, papel (75 x 110 cm) Sobre la superficie de cuatro hojas de papel, dos blancas y dos negras, percibimos los contornos de un texto reproducido cuatro veces con la ayuda de un molde : dos veces con p\u00f3lvora, dos veces con carb\u00f3n. La p\u00f3lvora y el carb\u00f3n han sido depositados directamente sobre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,23,14],"tags":[],"class_list":["post-788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insitu","category-autres","category-travaux"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["fr","es","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/comments?post=788"}],"version-history":[{"count":24,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/788\/revisions"}],"predecessor-version":[{"id":4066,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/788\/revisions\/4066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media\/2889"}],"wp:attachment":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media?parent=788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/categories?post=788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/tags?post=788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}