{"id":2148,"date":"2017-10-16T14:29:40","date_gmt":"2017-10-16T14:29:40","guid":{"rendered":"http:\/\/fragmentsliminaires.net\/?p=2148"},"modified":"2020-04-26T12:26:56","modified_gmt":"2020-04-26T11:26:56","slug":"et-ils-vont-dans-lespace-quembrasse-ton-regard","status":"publish","type":"post","link":"https:\/\/fragmentsliminaires.net\/es\/2017\/10\/16\/et-ils-vont-dans-lespace-quembrasse-ton-regard\/","title":{"rendered":"y van al espacio que abarca tu mirada: nos concierne"},"content":{"rendered":"<h5><span style=\"color: #999999;\">2016, 38 min 57, reproducci\u00f3n en continuo<\/span><\/h5>\n<h6><span style=\"color: #999999;\">Producci\u00f3n Jeu de Paume, Par\u00eds; c<\/span><span style=\"color: #999999;\">o-producci\u00f3n : Spectre<\/span><\/h6>\n<hr>\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/367775414\" allowfullscreen=\"\" width=\"800\" height=\"450\"><\/iframe>\n\n\n<p>Para decir que algo no nos concierne, se suele decir en franc\u00e9s \u201c\u00e7a ne nous regarde pas\u201d (literalmente: \u201cno nos mira\u201d). Aqu\u00ed la c\u00e1mara recorre el Centro de Retenci\u00f3n Administrativ<span style=\"text-decoration: line-through;\">o <\/span>Par\u00eds 1 (CRA), instalado en el l\u00edmite del bosque de Vincennes: es un largo travelling, filmado en plano secuencia, que adopta el punto de vista del edificio disimulado por el bosque. La noche del 21 de junio de 2008 estall\u00f3 una revuelta en este centro a ra\u00edz de la muerte, en su celda, de Salem Essouli, un migrante sin papeles, retenido a pesar de estar gravemente enfermo. En el curso del mot\u00edn, los \u201cretenidos\u201d quemaron dos pabellones del CRA. Pero nada de todo esto se pudo documentar visualmente desde el exterior. Lo que observamos aqu\u00ed es, pues, nuestra imposibilidad de ver lo que sucedi\u00f3 \u2013o lo que todav\u00eda sucede, puesto que recientemente hubo otro mot\u00edn, el 1\u00ba de julio de 2016\u2013, aunque esto nos concierne, (o \u201cnos mira\u201d), tanto \u00e9tica como pol\u00edticamente.<\/p>\n<p>Ver tambi\u00e9n: <a href=\"http:\/\/lemagazine.jeudepaume.org\/estefania-penafiel-loaiza\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"carnet du Jeu de Paume (s\u2019ouvre dans un nouvel onglet)\"><span style=\"color: #3366ff;\">carnet du Jeu de Paume<\/span><\/a><\/p>\n<hr \/>\n\n\n<div class=\"wp-block-soliloquy-soliloquywp\"><div aria-live=\"polite\" id=\"soliloquy-container-2789_1\" class=\"soliloquy-container soliloquy-transition-fade  soliloquy-theme-base\" style=\"max-width:960px;max-height:400px;\"><ul id=\"soliloquy-2789_1\" class=\"soliloquy-slider soliloquy-slides soliloquy-wrap soliloquy-clear\"><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-1 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2175\" class=\"soliloquy-image soliloquy-image-1\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj2a-960x400_c.jpg\" alt=\"EPLproj2a\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-2 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2177\" class=\"soliloquy-image soliloquy-image-2\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj4a-960x400_c.jpg\" alt=\"EPLproj4a\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-3 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2178\" class=\"soliloquy-image soliloquy-image-3\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj5a-960x400_c.jpg\" alt=\"EPLproj5a\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-4 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2176\" class=\"soliloquy-image soliloquy-image-4\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj3a-960x400_c.jpg\" alt=\"EPLproj3a\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-5 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2179\" class=\"soliloquy-image soliloquy-image-5\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj7a-960x400_c.jpg\" alt=\"EPLproj7a\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-6 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-2180\" class=\"soliloquy-image soliloquy-image-6\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2017\/10\/EPLproj8a-960x400_c.jpg\" alt=\"EPLproj8a\" \/><\/li><\/ul><\/div><noscript><style type=\"text\/css\">#soliloquy-container-2789_1{opacity:1}<\/style><\/noscript><\/div>\n","protected":false},"excerpt":{"rendered":"<p>2016, 38 min 57, reproducci\u00f3n en continuo Producci\u00f3n Jeu de Paume, Par\u00eds; co-producci\u00f3n : Spectre Para decir que algo no nos concierne, se suele decir en franc\u00e9s \u201c\u00e7a ne nous regarde pas\u201d (literalmente: \u201cno nos mira\u201d). Aqu\u00ed la c\u00e1mara recorre el Centro de Retenci\u00f3n Administrativo Par\u00eds 1 (CRA), instalado en el l\u00edmite del bosque de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,25,23,14,19],"tags":[],"class_list":["post-2148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insitu","category-series","category-autres","category-travaux","category-video-photo-film"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["fr","es","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/2148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":25,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/2148\/revisions"}],"predecessor-version":[{"id":3581,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/2148\/revisions\/3581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media\/2067"}],"wp:attachment":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media?parent=2148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/categories?post=2148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/tags?post=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}