{"id":1546,"date":"2016-01-22T16:42:09","date_gmt":"2016-01-22T16:42:09","guid":{"rendered":"http:\/\/fragmentsliminaires.net\/?p=1546"},"modified":"2024-08-08T13:28:36","modified_gmt":"2024-08-08T12:28:36","slug":"cartographies-1-la-crise-de-la-dimension","status":"publish","type":"post","link":"https:\/\/fragmentsliminaires.net\/es\/2016\/01\/22\/cartographies-1-la-crise-de-la-dimension\/","title":{"rendered":"cartograf\u00edas 1. la crisis de la dimensi\u00f3n"},"content":{"rendered":"<h5><span style=\"color: #808080;\">2010, v\u00eddeo HD (18 min 40) <span style=\"color: #ffffff;\">\/<\/span><br \/>\n<\/span><\/h5>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/349316025\" width=\"800\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Un libro abierto reposa sobre una mesa. La p\u00e1gina de la derecha no tiene texto impreso. Una mano entra en cuadro y recorre la p\u00e1gina blanca con las yemas de los dedos cargados de tinta. Al momento de rozar la p\u00e1gina, la tinta se imprime en la superficie y deja aparecer el texto que faltaba. Este video forma parte de una serie de trabajos que toman como materia el libro de Henri Michaux <strong><em>Ecuador<\/em><\/strong> (1929).<\/p>\n<p>Este trabajo forma parte de la serie: <a href=\"https:\/\/fragmentsliminaires.net\/es\/2017\/08\/03\/cartographies\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">\u00abcartograf\u00edas\u00bb<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>2010, v\u00eddeo HD (18 min 40) \/ Un libro abierto reposa sobre una mesa. La p\u00e1gina de la derecha no tiene texto impreso. Una mano entra en cuadro y recorre la p\u00e1gina blanca con las yemas de los dedos cargados de tinta. Al momento de rozar la p\u00e1gina, la tinta se imprime en la superficie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,14,19],"tags":[],"class_list":["post-1546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-travaux","category-video-photo-film"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["fr","es","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/1546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/comments?post=1546"}],"version-history":[{"count":10,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/1546\/revisions"}],"predecessor-version":[{"id":3596,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/posts\/1546\/revisions\/3596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media\/295"}],"wp:attachment":[{"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/media?parent=1546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/categories?post=1546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/es\/wp-json\/wp\/v2\/tags?post=1546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}