{"id":5938,"date":"2025-04-27T18:23:30","date_gmt":"2025-04-27T17:23:30","guid":{"rendered":"https:\/\/fragmentsliminaires.net\/?p=5938"},"modified":"2025-04-27T18:47:47","modified_gmt":"2025-04-27T17:47:47","slug":"111-iconos-del-arte-del-ecuador","status":"publish","type":"post","link":"https:\/\/fragmentsliminaires.net\/en\/2025\/04\/27\/111-iconos-del-arte-del-ecuador\/","title":{"rendered":"111 \u00edconos del arte del Ecuador"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"951\" height=\"945\" src=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE.webp\" alt=\"\" class=\"wp-image-5950\" srcset=\"https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE.webp 951w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE-300x298.webp 300w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE-150x150.webp 150w, https:\/\/fragmentsliminaires.net\/wp-content\/uploads\/2025\/04\/LIBRO-111ICONOS-DEL-ARTE-FRENTE-768x763.webp 768w\" sizes=\"auto, (max-width: 951px) 100vw, 951px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\">Autores : Mar\u00eda Fernanda Cartagena, Rafael Barriga, Juan Lorenzo Barrag\u00e1n.<\/p>\n\n\n\n<h5 class=\"wp-block-heading has-text-align-center\">Editorial Barrag\u00e1n Miller J. L., Quito, 248 p\u00e1ginas &#8211; <strong>ISBN<\/strong> 978-9942-48-518-2<\/h5>\n\n\n\n<p><em>Un inventario de los 111 \u00edconos m\u00e1s importantes de las obras pl\u00e1sticas del arte del Ecuador, desde la era precolombina hasta la actualidad, abarcando: era precolombina, colonia, rep\u00fablica, arte moderno y contempor\u00e1neo. Despliegan una imagen y un texto que ocupan dos p\u00e1ginas por cada \u00edcono. Adem\u00e1s, cuenta con pr\u00f3logo, introducci\u00f3n bibliograf\u00eda, \u00edndice y cr\u00e9ditos de las obras, y un glosario. Es una investigaci\u00f3n de Mar\u00eda Fernanda Cartagena, Rafael Barriga y Juna Lorenzo Barrag\u00e1n. Es el quinto volumen de la serie \u201cMi pa\u00eds: el Ecuador por los ojos\u201d.<\/em><\/p>\n\n\n\n<p>Entre los 111 trabajos que integran este volumen se cuenta la obra &#8220;<a href=\"https:\/\/fragmentsliminaires.net\/2016\/01\/22\/compte-a-rebours-2\/\">cuenta regresiva<\/a>&#8221; (2005-2013) de Estefan\u00eda Pe\u00f1afiel Loaiza, presentada por Rafael Barriga:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-left\">La obra de Estefan\u00eda Pe\u00f1afiel Loaiza explora los desplazamientos, las geograf\u00edas y la fragilidad de la memoria. Su inter\u00e9s por repensar e interpretar procesos hist\u00f3ricos, llev\u00e1ndolos al presente, se refleja en videos, acciones, instalaciones y trabajo con archivos, creando piezas de profundo significado y cuidadosa elaboraci\u00f3n. <\/p>\n\n\n\n<p class=\"has-text-align-left\">Radicada en Par\u00eds desde 2002, su trayectoria art\u00edstica ha sido fruct\u00edfera. <em>Cuenta regresiva<\/em>, adquirida por el Centro Pompidou para su colecci\u00f3n permanente, es una serie de videos que suman 105. En ellos, la artista lee el contenido completo de las 18 constituciones pol\u00edticas aprobadas desde la fundaci\u00f3n del pa\u00eds. La lectura se realiza en diversos lugares de Ecuador, Francia y B\u00e9lgica.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Lo fascinante es que Estefan\u00eda lee al rev\u00e9s, comenzando desde el \u00faltimo fonema de la \u00faltima palabra de la Constituci\u00f3n, para entonces reciente (1998), hasta el primero de la primera constituci\u00f3n (1830). En la edici\u00f3n final, invierte la secuencia, creando un efecto extra\u00f1o y cacof\u00f3nico que, sin embargo, recobra cierto sentido. Un momento impactante ocurre durante la lectura frente a la Asamblea Nacional: un torbellino de viento, polvo y escombros derrumba la puerta principal del edificio, como si la naturaleza misma quisiera protestar ante la farsa hist\u00f3rica que la obra denuncia. Esta pieza nos invita a reflexionar sobre la construccci\u00f3n de la historia y la identidad nacionales, cuestionando la estabilidad de las instituciones y la permanencia de las leyes fundamentales. <\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autores : Mar\u00eda Fernanda Cartagena, Rafael Barriga, Juan Lorenzo Barrag\u00e1n. Editorial Barrag\u00e1n Miller J. L., Quito, 248 p\u00e1ginas &#8211; ISBN 978-9942-48-518-2 Un inventario de los 111 \u00edconos m\u00e1s importantes de las obras pl\u00e1sticas del arte del Ecuador, desde la era precolombina hasta la actualidad, abarcando: era precolombina, colonia, rep\u00fablica, arte moderno y contempor\u00e1neo. Despliegan una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,60,43],"tags":[],"class_list":["post-5938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-publications","category-publications-catalogues-monographies"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["fr","es","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/posts\/5938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/comments?post=5938"}],"version-history":[{"count":6,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/posts\/5938\/revisions"}],"predecessor-version":[{"id":5960,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/posts\/5938\/revisions\/5960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/media\/5941"}],"wp:attachment":[{"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/media?parent=5938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/categories?post=5938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fragmentsliminaires.net\/en\/wp-json\/wp\/v2\/tags?post=5938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}